{"id":2225,"date":"2025-02-12T12:31:59","date_gmt":"2025-02-12T11:31:59","guid":{"rendered":"https:\/\/mobac.schmittz-design.de\/?page_id=2225"},"modified":"2025-05-08T15:16:06","modified_gmt":"2025-05-08T13:16:06","slug":"payoffs","status":"publish","type":"page","link":"https:\/\/mobac.de\/en\/products\/winding-machines\/payoffs\/","title":{"rendered":"Unwinder"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f5f5f5&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;50&#8243; bottom_padding=&#8221;50&#8243; bottom_margin=&#8221;50&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.8&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Winding machines&#8221; font_container=&#8221;tag:h4|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221; el_class=&#8221;h4-grey&#8221;][vc_custom_heading text=&#8221;Unwinder&#8221; font_container=&#8221;tag:h1|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221; el_class=&#8221;h1-orange&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Braked or driven type unwinders developed for the precise and controlled unwinding of wires, cables and ropes. They enable tangential removal of the material from the spool, which is particularly advantageous for sensitive or high-precision applications.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;4873&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;150%&#8221; max_width_mobile=&#8221;default&#8221; translate_y_desktop=&#8221;0&#8243; translate_x_desktop=&#8221;-30%&#8221; translate_y_tablet=&#8221;-30%&#8221; translate_x_tablet=&#8221;0&#8243; translate_y_phone=&#8221;-30%&#8221; translate_x_phone=&#8221;0&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;50&#8243; bottom_padding=&#8221;50&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column top_padding_desktop=&#8221;4%&#8221; bottom_padding_desktop=&#8221;3%&#8221; left_padding_desktop=&#8221;3%&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;3%&#8221; top_padding_tablet=&#8221;4%&#8221; constrain_group_102=&#8221;yes&#8221; bottom_padding_tablet=&#8221;4%&#8221; left_padding_tablet=&#8221;3%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;3%&#8221; top_padding_phone=&#8221;7%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;7%&#8221; left_padding_phone=&#8221;5%&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;15px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_color=&#8221;#002b57&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;40&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2>Driven tangential payoffs with single-sided, double-sided or multiple spool take-up<\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Driven tangential pay-offs with single-sided, double-sided or multiple spool take-up ensure precise wire feeding and tension control. They can be flexibly adapted to spool sizes and wire speeds. The manual or powered dancer controls the constant wire tension and adjusts the speed.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.5&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_gallery css=&#8221;&#8221; type=&#8221;flickity_static_height_style&#8221; images=&#8221;5328,5329,5330,5331,5332,5333,5334,5087,5086,5085,5084,5083,5082,5081,5080,5079,5078,5077,5076,5075,5074,5073,5072,5071,5070,5069,5068,5067,5066&#8243; flickity_spacing=&#8221;default&#8221; flickity_controls=&#8221;material_pagination&#8221; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_box_shadow=&#8221;small_depth&#8221; image_loading=&#8221;default&#8221; display_title_caption=&#8221;true&#8221; onclick=&#8221;link_image&#8221; img_size=&#8221;full&#8221; flickity_img_height=&#8221;250&#8243; flickity_img_mobile_height=&#8221;150&#8243;][\/vc_column_inner][\/vc_row_inner][tabbed_section style=&#8221;minimal_flexible&#8221; tab_color=&#8221;Extra-Color-1&#8243; vs_content_animation=&#8221;fade&#8221; vs_link_animation=&#8221;opacity&#8221; vs_navigation_alignment=&#8221;left&#8221; vs_navigation_width_2=&#8221;25%&#8221; vs_navigation_func=&#8221;default&#8221; vs_navigation_width=&#8221;regular&#8221; vs_navigation_spacing=&#8221;15px&#8221; vs_navigation_mobile_display=&#8221;visible&#8221; vs_tab_spacing=&#8221;5%&#8221; icon_size=&#8221;32&#8243;][tab icon_family=&#8221;none&#8221; title=&#8221;Details&#8221; id=&#8221;1746708004030-9&#8243; tab_id=&#8221;1746708004031-7&#8243; el_class=&#8221;tab-details&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h4>Description<\/h4>\n<ul>\n<li>Spool diameter: 80 to 1000 mm<\/li>\n<li>Number of winding positions: up to 30 (customer-specific)<\/li>\n<li>Maximum wire speed: up to 600 m\/min<\/li>\n<li>Supported wire \/ cable diameters: 0.05 to 8 mm<\/li>\n<li>Maximum spool weight: up to 800 kg (depending on the spool type)<\/li>\n<li>Wire tension range: 0.5 to 200 N<\/li>\n<li>Spool change: &lt;30 seconds<\/li>\n<li>Drive: three-phase motor with frequency converter, power up to 7.5 kW<\/li>\n<li>Material compatibility: copper and steel wires, cables and carbon fibers<\/li>\n<li>Available with single-sided, double-sided or multiple spool holder<\/li>\n<li>Integrated wire break sensors for increased operational safety<\/li>\n<li>Optional protective hoods or protective grilles for occupational safety<\/li>\n<li>Deflection rollers after the spool for smooth wire running<\/li>\n<li>Adjustable wire tension manually or via servo motor for precise process control<\/li>\n<li>Modular design enables<\/li>\n<li>Robust construction for continuous industrial use<\/li>\n<li>Simple integration into existing production lines (stand-alone)<\/li>\n<li>Maintenance-friendly design to minimize downtime<\/li>\n<li>High operational reliability thanks to high-quality components<\/li>\n<li>Flexibility to process different wire types and sizes<\/li>\n<li>Optimized for high production speeds<\/li>\n<li>Customizable settings for different material requirements<\/li>\n<li>Durable materials for an extended service life<\/li>\n<li>Low-noise operation for a pleasant working environment<\/li>\n<li>Safety devices to protect the operating personnel<\/li>\n<li>Detailed technical documentation and support available<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h4>Optional<\/h4>\n<ul>\n<li data-start=\"1170\" data-end=\"1234\">Electrohydraulic spool tensioning for automated processes<\/li>\n<li data-start=\"1235\" data-end=\"1301\">Customizable flange diameters depending on specific requirements<\/li>\n<li data-start=\"1302\" data-end=\"1374\">Special adaptations for different wire diameters and types<\/li>\n<li data-start=\"1375\" data-end=\"1444\">Integration of additional sensors for extended process monitoring<\/li>\n<li data-start=\"1445\" data-end=\"1491\">Customized modifications on request<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/tab][\/tabbed_section][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;50&#8243; bottom_padding=&#8221;50&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column top_padding_desktop=&#8221;4%&#8221; bottom_padding_desktop=&#8221;3%&#8221; left_padding_desktop=&#8221;3%&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;3%&#8221; top_padding_tablet=&#8221;4%&#8221; constrain_group_102=&#8221;yes&#8221; bottom_padding_tablet=&#8221;4%&#8221; left_padding_tablet=&#8221;3%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;3%&#8221; top_padding_phone=&#8221;7%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;7%&#8221; left_padding_phone=&#8221;5%&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;15px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_color=&#8221;#002b57&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;40&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2>Driven tangential payoffs with pinole clamping system<\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Driven tangential pay-offs with a pinole clamping system ensure precise wire feeding and tension control. They can be flexibly adapted to spool sizes and wire speeds. The manual or powered dancer controls the constant wire tension and adjusts the speed. The spools are lifted and clamped either manually or using electro-hydraulics.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.5&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_gallery css=&#8221;&#8221; type=&#8221;flickity_static_height_style&#8221; images=&#8221;5341,5342,5090,5089,5088,5335,5336,5337,5338,5339,5340&#8243; flickity_spacing=&#8221;default&#8221; flickity_controls=&#8221;pagination&#8221; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_box_shadow=&#8221;small_depth&#8221; image_loading=&#8221;default&#8221; display_title_caption=&#8221;true&#8221; onclick=&#8221;link_image&#8221; img_size=&#8221;full&#8221; flickity_img_height=&#8221;250&#8243; flickity_img_mobile_height=&#8221;150&#8243;][\/vc_column_inner][\/vc_row_inner][tabbed_section style=&#8221;minimal_flexible&#8221; tab_color=&#8221;Extra-Color-1&#8243; vs_content_animation=&#8221;fade&#8221; vs_link_animation=&#8221;opacity&#8221; vs_navigation_alignment=&#8221;left&#8221; vs_navigation_width_2=&#8221;25%&#8221; vs_navigation_func=&#8221;default&#8221; vs_navigation_width=&#8221;regular&#8221; vs_navigation_spacing=&#8221;15px&#8221; vs_navigation_mobile_display=&#8221;visible&#8221; vs_tab_spacing=&#8221;5%&#8221; icon_size=&#8221;32&#8243;][tab icon_family=&#8221;none&#8221; title=&#8221;Details&#8221; id=&#8221;1746708005786-3&#8243; tab_id=&#8221;1746708005787-10&#8243; el_class=&#8221;tab-details&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h4>Description<\/h4>\n<ul>\n<li>Spool diameter: 250 to 1600 mm<\/li>\n<li>Maximum wire speed: up to 800 m\/min<\/li>\n<li>Supported wire \/ cable diameters: 0.1 to 20 mm<\/li>\n<li>Maximum spool weight: up to 2000 kg (depending on the spool type)<\/li>\n<li>Wire tension range: up to 300 N<\/li>\n<li>Spool change: &lt;60 seconds<\/li>\n<li>Drive: Three-phase motor with frequency converter, power up to 11 kW<\/li>\n<li>Material compatibility: copper and steel wires, cables and carbon fibers<\/li>\n<li>Integrated wire break sensors for increased operational safety<\/li>\n<li>Optional protective hoods or protective grilles for occupational safety<\/li>\n<li>Deflection rollers after the spool for smooth wire running<\/li>\n<li>Adjustable wire tension manually or via servo motor for precise process control<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h4>Optional<\/h4>\n<ul>\n<li>Customizable spool dimensions depending on specific requirements<\/li>\n<li>Special adaptations for different wire diameters and types<\/li>\n<li>Integration of additional sensors for extended process monitoring<\/li>\n<li>Wire break switch<\/li>\n<li>Large digital display<\/li>\n<li>Foldable operating consoles<\/li>\n<li>Dancer accumulator with servo motor<\/li>\n<li>Wire clamp (mech.\/electr.)<\/li>\n<li>Interfaces e.g. for printers, spark testers etc.<br \/>\nTerminal for entering and saving winding data<br \/>\nController with interface for PLC communication<\/li>\n<li>Product-specific wire guides<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/tab][\/tabbed_section][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;50&#8243; bottom_padding=&#8221;50&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column top_padding_desktop=&#8221;4%&#8221; bottom_padding_desktop=&#8221;3%&#8221; left_padding_desktop=&#8221;3%&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;3%&#8221; top_padding_tablet=&#8221;4%&#8221; constrain_group_102=&#8221;yes&#8221; bottom_padding_tablet=&#8221;4%&#8221; left_padding_tablet=&#8221;3%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;3%&#8221; top_padding_phone=&#8221;7%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;7%&#8221; left_padding_phone=&#8221;5%&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;15px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_color=&#8221;#002b57&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;40&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2>Tangential payoffs (braked) with shaft on one or both sides<\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Tangential pay-offs with a shaft on one or both sides enable the precise unwinding of wires and cables with controlled tension.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.5&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_gallery css=&#8221;&#8221; type=&#8221;flickity_static_height_style&#8221; images=&#8221;5092,5093,5094,5095,5096,5098,5099,5100,5101,5102,5103,5104,5105&#8243; flickity_spacing=&#8221;default&#8221; flickity_controls=&#8221;pagination&#8221; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_box_shadow=&#8221;small_depth&#8221; image_loading=&#8221;default&#8221; display_title_caption=&#8221;true&#8221; onclick=&#8221;link_image&#8221; img_size=&#8221;full&#8221; flickity_img_height=&#8221;250&#8243; flickity_img_mobile_height=&#8221;150&#8243;][\/vc_column_inner][\/vc_row_inner][tabbed_section style=&#8221;minimal_flexible&#8221; tab_color=&#8221;Extra-Color-1&#8243; vs_content_animation=&#8221;fade&#8221; vs_link_animation=&#8221;opacity&#8221; vs_navigation_alignment=&#8221;left&#8221; vs_navigation_width_2=&#8221;25%&#8221; vs_navigation_func=&#8221;default&#8221; vs_navigation_width=&#8221;regular&#8221; vs_navigation_spacing=&#8221;15px&#8221; vs_navigation_mobile_display=&#8221;visible&#8221; vs_tab_spacing=&#8221;5%&#8221; icon_size=&#8221;32&#8243;][tab icon_family=&#8221;none&#8221; title=&#8221;Details&#8221; id=&#8221;1746708007489-1&#8243; tab_id=&#8221;1746708007489-1&#8243; el_class=&#8221;tab-details&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h4>Description<\/h4>\n<ul>\n<li>Spool diameter: 125-1250 mm<\/li>\n<li>Wire diameter: 0.2-25.0 mm<\/li>\n<li>Maximum spool width: up to 800 mm<\/li>\n<li>Maximum unwinding speed up to 300 m\/min (depending on model)<\/li>\n<li>Permanent or current-controlled hysteresis brakes and magnetic particle brakes with a power supply unit are used as braking systems<\/li>\n<li>Spool holder: shaft mounted on one side with Easylock clamping system or similar incl. Driver<\/li>\n<li>Maximum spool weight: up to 1000 kg<\/li>\n<li>Spool change time: &lt;15 seconds<\/li>\n<li>Independent brake control for double-sided or multiple reel pick-up<\/li>\n<li>Dancer accumulator for adjusting the tension and tensile force (depending on model) (optional)<\/li>\n<li>Modular design for different applications<\/li>\n<li>Use for various wire materials such as copper, aluminum, steel, plastic, carbon fiber, ropes<\/li>\n<li>Customized adaptations possible<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h4>Optional<\/h4>\n<ul>\n<li>Wire break switch<\/li>\n<li>Tensile force sensors with digital display<\/li>\n<li>Constant tension control during unwinding<\/li>\n<li>Protective device<\/li>\n<li>Under-sink frame<\/li>\n<li>Dancer accumulator<\/li>\n<li>Multiple sequences up to 30 spool positions (depending on model)<\/li>\n<li>Wire clamp<\/li>\n<li>Product-specific wire guides<\/li>\n<li>Fixed and swivel castors under the tangential drain<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/tab][\/tabbed_section][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;50&#8243; bottom_padding=&#8221;50&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column top_padding_desktop=&#8221;4%&#8221; bottom_padding_desktop=&#8221;3%&#8221; left_padding_desktop=&#8221;3%&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;3%&#8221; top_padding_tablet=&#8221;4%&#8221; constrain_group_102=&#8221;yes&#8221; bottom_padding_tablet=&#8221;4%&#8221; left_padding_tablet=&#8221;3%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;3%&#8221; top_padding_phone=&#8221;7%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;7%&#8221; left_padding_phone=&#8221;5%&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;15px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_color=&#8221;#002b57&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;40&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2>Tangential payoffs (braked) with pinole clamping system<\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Tangential pay-offs with pinole clamping system use hand lever hydraulics to lift and tension the reel for efficient unwinding.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.5&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_gallery css=&#8221;&#8221; type=&#8221;flickity_static_height_style&#8221; images=&#8221;5343,5344,5345,5346&#8243; flickity_spacing=&#8221;default&#8221; flickity_controls=&#8221;pagination&#8221; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_box_shadow=&#8221;small_depth&#8221; image_loading=&#8221;default&#8221; display_title_caption=&#8221;true&#8221; onclick=&#8221;link_image&#8221; img_size=&#8221;full&#8221; flickity_img_height=&#8221;250&#8243; flickity_img_mobile_height=&#8221;150&#8243;][\/vc_column_inner][\/vc_row_inner][tabbed_section style=&#8221;minimal_flexible&#8221; tab_color=&#8221;Extra-Color-1&#8243; vs_content_animation=&#8221;fade&#8221; vs_link_animation=&#8221;opacity&#8221; vs_navigation_alignment=&#8221;left&#8221; vs_navigation_width_2=&#8221;25%&#8221; vs_navigation_func=&#8221;default&#8221; vs_navigation_width=&#8221;regular&#8221; vs_navigation_spacing=&#8221;15px&#8221; vs_navigation_mobile_display=&#8221;visible&#8221; vs_tab_spacing=&#8221;5%&#8221; icon_size=&#8221;32&#8243;][tab icon_family=&#8221;none&#8221; title=&#8221;Details&#8221; id=&#8221;1746708008886-7&#8243; tab_id=&#8221;1746708008887-9&#8243; el_class=&#8221;tab-details&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h4>Description<\/h4>\n<ul>\n<li>Spool diameter: 355-2800 mm<\/li>\n<li>Wire diameter: 0.2-30.0 mm<\/li>\n<li>Maximum spool width: up to 1000 mm<\/li>\n<li>Maximum unwinding speed up to 300 m\/min (depending on model)<\/li>\n<li>Permanent or current-controlled hysteresis brakes and magnetic particle brakes with a power supply unit are used as braking systems<\/li>\n<li>Spool holder: via a sleeve incl. Driver<\/li>\n<li>Spool lifting via manual or electro-hydraulic system<\/li>\n<li>Spool tensioning by hand or via electrohydraulics<\/li>\n<li>Maximum spool weight: up to 5000 kg<\/li>\n<li>Spool change time: &lt;60 seconds<\/li>\n<li>Dancer accumulator for adjusting the tension and tensile force (depending on model) (optional)<\/li>\n<li>Use for various wire materials such as copper, aluminum, steel, plastic, carbon fiber, ropes<\/li>\n<li>Customized adaptations possible<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h4>Optional<\/h4>\n<ul>\n<li>Wire break switch<\/li>\n<li>Tensile force sensors with digital display<\/li>\n<li>Constant tension control during unwinding<\/li>\n<li>Protective device<\/li>\n<li>Dancer accumulator<\/li>\n<li>Wire clamp<\/li>\n<li>Product-specific wire guides<\/li>\n<li>Fixed and swivel castors under the tangential drain (depending on model)<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/tab][\/tabbed_section][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f5f5f5&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;50&#8243; bottom_padding=&#8221;50&#8243; bottom_margin=&#8221;50&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.8&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":4344,"parent":1788,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-2225","page","type-page","status-publish","has-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unwinder &#8211; mobac GmbH<\/title>\n<meta name=\"description\" content=\"Precise winders and unwinders for wire, cable and rope: a wide range of models for efficient winding in industrial applications.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mobac.de\/en\/products\/winding-machines\/payoffs\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unwinder &#8211; mobac GmbH\" \/>\n<meta property=\"og:description\" content=\"Precise winders and unwinders for wire, cable and rope: a wide range of models for efficient winding in industrial applications.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mobac.de\/en\/products\/winding-machines\/payoffs\/\" \/>\n<meta property=\"og:site_name\" content=\"mobac GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-08T13:16:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mobac.de\/wp-content\/uploads\/2025\/03\/image-256.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"430\" \/>\n\t<meta property=\"og:image:height\" content=\"446\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mobac.de\\\/en\\\/products\\\/winding-machines\\\/payoffs\\\/\",\"url\":\"https:\\\/\\\/mobac.de\\\/en\\\/products\\\/winding-machines\\\/payoffs\\\/\",\"name\":\"Unwinder &#8211; mobac GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mobac.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mobac.de\\\/en\\\/products\\\/winding-machines\\\/payoffs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mobac.de\\\/en\\\/products\\\/winding-machines\\\/payoffs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mobac.de\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/image-256.jpeg\",\"datePublished\":\"2025-02-12T11:31:59+00:00\",\"dateModified\":\"2025-05-08T13:16:06+00:00\",\"description\":\"Precise winders and unwinders for wire, cable and rope: a wide range of models for efficient winding in industrial applications.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mobac.de\\\/en\\\/products\\\/winding-machines\\\/payoffs\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mobac.de\\\/en\\\/products\\\/winding-machines\\\/payoffs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mobac.de\\\/en\\\/products\\\/winding-machines\\\/payoffs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mobac.de\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/image-256.jpeg\",\"contentUrl\":\"https:\\\/\\\/mobac.de\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/image-256.jpeg\",\"width\":430,\"height\":446},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mobac.de\\\/en\\\/products\\\/winding-machines\\\/payoffs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/mobac.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/mobac.de\\\/en\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Winding machines\",\"item\":\"https:\\\/\\\/mobac.de\\\/en\\\/products\\\/winding-machines\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Unwinder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mobac.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mobac.de\\\/en\\\/\",\"name\":\"mobac GmbH\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mobac.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mobac.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mobac.de\\\/en\\\/#organization\",\"name\":\"mobac GmbH\",\"url\":\"https:\\\/\\\/mobac.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mobac.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mobac.de\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/mobac_Logo_4_blau-mit-Claim.png\",\"contentUrl\":\"https:\\\/\\\/mobac.de\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/mobac_Logo_4_blau-mit-Claim.png\",\"width\":1920,\"height\":688,\"caption\":\"mobac GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/mobac.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mobac\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unwinder &#8211; mobac GmbH","description":"Precise winders and unwinders for wire, cable and rope: a wide range of models for efficient winding in industrial applications.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mobac.de\/en\/products\/winding-machines\/payoffs\/","og_locale":"en_US","og_type":"article","og_title":"Unwinder &#8211; mobac GmbH","og_description":"Precise winders and unwinders for wire, cable and rope: a wide range of models for efficient winding in industrial applications.","og_url":"https:\/\/mobac.de\/en\/products\/winding-machines\/payoffs\/","og_site_name":"mobac GmbH","article_modified_time":"2025-05-08T13:16:06+00:00","og_image":[{"width":430,"height":446,"url":"https:\/\/mobac.de\/wp-content\/uploads\/2025\/03\/image-256.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mobac.de\/en\/products\/winding-machines\/payoffs\/","url":"https:\/\/mobac.de\/en\/products\/winding-machines\/payoffs\/","name":"Unwinder &#8211; mobac GmbH","isPartOf":{"@id":"https:\/\/mobac.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mobac.de\/en\/products\/winding-machines\/payoffs\/#primaryimage"},"image":{"@id":"https:\/\/mobac.de\/en\/products\/winding-machines\/payoffs\/#primaryimage"},"thumbnailUrl":"https:\/\/mobac.de\/wp-content\/uploads\/2025\/03\/image-256.jpeg","datePublished":"2025-02-12T11:31:59+00:00","dateModified":"2025-05-08T13:16:06+00:00","description":"Precise winders and unwinders for wire, cable and rope: a wide range of models for efficient winding in industrial applications.","breadcrumb":{"@id":"https:\/\/mobac.de\/en\/products\/winding-machines\/payoffs\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mobac.de\/en\/products\/winding-machines\/payoffs\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mobac.de\/en\/products\/winding-machines\/payoffs\/#primaryimage","url":"https:\/\/mobac.de\/wp-content\/uploads\/2025\/03\/image-256.jpeg","contentUrl":"https:\/\/mobac.de\/wp-content\/uploads\/2025\/03\/image-256.jpeg","width":430,"height":446},{"@type":"BreadcrumbList","@id":"https:\/\/mobac.de\/en\/products\/winding-machines\/payoffs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/mobac.de\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/mobac.de\/en\/products\/"},{"@type":"ListItem","position":3,"name":"Winding machines","item":"https:\/\/mobac.de\/en\/products\/winding-machines\/"},{"@type":"ListItem","position":4,"name":"Unwinder"}]},{"@type":"WebSite","@id":"https:\/\/mobac.de\/en\/#website","url":"https:\/\/mobac.de\/en\/","name":"mobac GmbH","description":"","publisher":{"@id":"https:\/\/mobac.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mobac.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mobac.de\/en\/#organization","name":"mobac GmbH","url":"https:\/\/mobac.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mobac.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mobac.de\/wp-content\/uploads\/2024\/10\/mobac_Logo_4_blau-mit-Claim.png","contentUrl":"https:\/\/mobac.de\/wp-content\/uploads\/2024\/10\/mobac_Logo_4_blau-mit-Claim.png","width":1920,"height":688,"caption":"mobac GmbH"},"image":{"@id":"https:\/\/mobac.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/mobac\/"]}]}},"_links":{"self":[{"href":"https:\/\/mobac.de\/en\/wp-json\/wp\/v2\/pages\/2225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mobac.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mobac.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mobac.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mobac.de\/en\/wp-json\/wp\/v2\/comments?post=2225"}],"version-history":[{"count":10,"href":"https:\/\/mobac.de\/en\/wp-json\/wp\/v2\/pages\/2225\/revisions"}],"predecessor-version":[{"id":5350,"href":"https:\/\/mobac.de\/en\/wp-json\/wp\/v2\/pages\/2225\/revisions\/5350"}],"up":[{"embeddable":true,"href":"https:\/\/mobac.de\/en\/wp-json\/wp\/v2\/pages\/1788"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mobac.de\/en\/wp-json\/wp\/v2\/media\/4344"}],"wp:attachment":[{"href":"https:\/\/mobac.de\/en\/wp-json\/wp\/v2\/media?parent=2225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}